{"id":4832,"date":"2023-04-26T21:22:11","date_gmt":"2023-04-26T21:22:11","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/26\/conceden-al-rector-dr-jesus-maduena-molina-la-suspension-definitiva-contra-la-aplicacion-de-la-ley-de-educacion-superior-del-estado-de-sinaloa\/"},"modified":"2025-06-24T22:24:57","modified_gmt":"2025-06-24T22:24:57","slug":"conceden-al-rector-dr-jesus-maduena-molina-la-suspension-definitiva-contra-la-aplicacion-de-la-ley-de-educacion-superior-del-estado-de-sinaloa","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/26\/conceden-al-rector-dr-jesus-maduena-molina-la-suspension-definitiva-contra-la-aplicacion-de-la-ley-de-educacion-superior-del-estado-de-sinaloa\/","title":{"rendered":"Conceden al Rector, Dr. Jes\u00fas Madue\u00f1a Molina la suspensi\u00f3n definitiva contra la aplicaci\u00f3n de la Ley de Educaci\u00f3n Superior del Estado de Sinaloa"},"content":{"rendered":"<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/WhatsApp_Image_2023-04-26_at_13.36.11.jpg\" alt=\"WhatsApp Image 2023 04 26 at 13.36.11\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><\/div>\n<div>&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">El Juez Tercero de Distrito concedi\u00f3 al Rector de la Universidad Aut\u00f3noma de Sinaloa (UAS), doctor Jes\u00fas Madue\u00f1a Molina, y presidente del H. Consejo Universitario, la suspensi\u00f3n definitiva al amparo interpuesto en contra de la aplicaci\u00f3n de Ley de Educaci\u00f3n Superior del Estado de Sinaloa, que se suma a las 15 suspensiones definitivas y 78 provisionales que ya se hab\u00edan concedido.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">Durante el evento de firma de Convenio con Unidades Receptoras de Pr\u00e1cticas Profesionales en la ciudad de Mazatl\u00e1n, y previamente en entrevista con medios de comunicaci\u00f3n locales, el Rector inform\u00f3 de la resoluci\u00f3n del Juez de la suspensi\u00f3n definitiva solicitada para el efecto de que se impidan los efectos y consecuencias de las normas reclamadas en la esfera jur\u00eddica de la parte quejosa correspondiente al Art\u00edculo 3ro, p\u00e1rrafo III y IV, art\u00edculo 19 y 51 fracci\u00f3n VIII, art\u00edculo 59 y 69 fracciones IX y X, de la Ley de Educaci\u00f3n Superior del Estado de Sinaloa.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\"><\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">\u201cGracias a la justicia federal en este momento hemos podido mantener y sostener el que no siga la intromisi\u00f3n del Congreso del Estado (\u2026) nos hab\u00edan dado la suspensi\u00f3n provisional y nos acaban de dar la suspensi\u00f3n definitiva de varios art\u00edculos de la Ley de Educaci\u00f3n Superior que vulnera la Autonom\u00eda Universitaria, por eso hoy nos sentimos tranquilos y tambi\u00e9n contentos porque la justicia federal le est\u00e1 dando la raz\u00f3n a la Universidad Aut\u00f3noma de Sinaloa\u201d, expres\u00f3 el Rector.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\"><\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">Se\u00f1al\u00f3 que los diputados salen todos los d\u00edas a los medios de comunicaci\u00f3n a distorsionar lo que realmente est\u00e1 pasando, pero la verdad se puede consultar en los tribunales federales.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">\u201cDecirle a los j\u00f3venes que vamos a seguir trabajando para seguir generando confianza en la relaci\u00f3n con el sector empresarial, con los sectores productivos, con los padres de familia, vamos a seguir trabajando por la transparencia y la rendici\u00f3n de cuentas, porque es otro tema que quieren ellos plantar como relator\u00eda en los medios cuando dicen que la Universidad se niega a ser auditada, jam\u00e1s, y la m\u00e1s vil mentira es esa\u201d, dijo, al citar que la Auditor\u00eda Superior de la Federaci\u00f3n (ASF) est\u00e1 auditando a la instituci\u00f3n, adem\u00e1s se cuenta con una Contralor\u00eda Social integrada por representantes de Gobierno del Estado, del Congreso, padres de familia y sectores productivos y profesionistas quienes auditan los recursos.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">El Rector enfatiz\u00f3 que esto demuestra que la Universidad siempre ha comunicado la verdad con la evidencia en mano, sin hacer actos medi\u00e1ticos con mentiras.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">\u201cEstamos trabajando respetando el estado de derecho, creemos en la justicia federal y vamos a hacer lo que la justicia federal nos ordene, por lo que vamos a seguir trabajando de manera tranquila, arm\u00f3nica\u201d, manifest\u00f3 ante los medios.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\"><\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">El abogado general de la UAS, doctor Robespierre Liz\u00e1rraga Otero, detall\u00f3 que la resoluci\u00f3n del juez tiene como efecto que se ordene al Congreso de Estado que no puede convocar ni organizar consultas en la UAS para modificar la Ley Org\u00e1nica, ni obstaculizar la administraci\u00f3n de recursos econ\u00f3micos a la Universidad; tampoco puede emitir orden de comparecencia al Rector, y se ordena a las autoridades responsables no emitir actos que afecten la vida interna universitaria y no denosten la honorabilidad de la universidad ante los medios de comunicaci\u00f3n as\u00ed como evitar hacer cualquier medida, diligencia o requerimiento sobre los ingresos propios de la Casa Rosalina.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\"><\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">\u201cLa justicia federal est\u00e1 protegiendo a la Universidad sobre cualquier afectaci\u00f3n que se pueda dar en los efectos se\u00f1alados (\u2026) confirmamos categ\u00f3ricamente que cualquier aseveraci\u00f3n, expresi\u00f3n o manifestaci\u00f3n en contrario est\u00e1 faltando a la verdad, esta es la verdad y aunque los diputados no lo quieran deben aceptar, tiene que acatar esta orden de un juez o pueden ser sancionados\u201d, dijo.<\/span><\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>Redacci\u00f2n\/ Vision Ciudadana&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; El Juez Tercero de Distrito concedi\u00f3 al Rector de la Universidad Aut\u00f3noma de Sinaloa (UAS), doctor Jes\u00fas Madue\u00f1a Molina, y presidente del H. Consejo Universitario, la suspensi\u00f3n definitiva al amparo interpuesto en contra de la aplicaci\u00f3n de Ley de Educaci\u00f3n Superior del Estado de Sinaloa, que se suma a las 15 suspensiones definitivas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4832"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4832\/revisions"}],"predecessor-version":[{"id":27959,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4832\/revisions\/27959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4831"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4832"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}