{"id":4752,"date":"2023-04-19T23:32:24","date_gmt":"2023-04-19T23:32:24","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/19\/morena-no-quiere-al-campo-sinaloense-pan\/"},"modified":"2025-06-24T22:25:00","modified_gmt":"2025-06-24T22:25:00","slug":"morena-no-quiere-al-campo-sinaloense-pan","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/19\/morena-no-quiere-al-campo-sinaloense-pan\/","title":{"rendered":"Morena no quiere al campo sinaloense: PAN"},"content":{"rendered":"<div style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/2023\/Abril23\/roxan.jpg\" alt=\"roxan\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Que el gobierno federal invierta en el rescate del campo en vez de estar tirando el dinero en precampa\u00f1as de sus corcholatas: Roxana Rubio<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">La Presidenta del PAN Sinaloa, Roxana Rubio Valdez, declar\u00f3 en conferencia de prensa que urge que el gobierno federal se comprometa con el rescate del campo mexicano, en vez de estar invirtiendo en precampa\u00f1as ilegales y en otros rubros que no dejan ning\u00fan beneficio para el estado ni para el pa\u00eds.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cEl PAN est\u00e1 a favor del campo, los productores son parte esencial de nuestro estado, gracias a ellos somos conocidos como \u201cel granero de M\u00e9xico\u201d y es por ello que no me parece justo que cada temporada est\u00e9n preocupados por el precio que les dar\u00e1n por sus cosechas\u201d, dijo.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cSe necesitan 7 mil 500 millones de pesos para rescatar el campo del pa\u00eds y por supuesto que los tiene el gobierno federal, pero prefieren invertirlos en precampa\u00f1as que son ilegales, prefieren invertirlos en las corcholatas y en la compra de votos, ojal\u00e1 que se solucione este problema porque no solo es en Sinaloa, sino en todo el pa\u00eds\u201d, enfatiz\u00f3.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Rubio Valdez indic\u00f3 que los productores de ma\u00edz piden siete mil pesos por tonelada, ya que todos los insumos han aumentado; la semilla es m\u00e1s cara, al igual que la cuota de agua, los fertilizantes y los costos de producci\u00f3n.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cCreo que es tiempo de que las autoridades les presten la atenci\u00f3n y que no nada m\u00e1s les est\u00e9n dando atole con el dedo de que van y gestionan al gobierno federal pero no pasa absolutamente nada, creo que es justo y se merecen esos precios que est\u00e1n solicitando. Estos productores vienen haciendo lo mismo generaci\u00f3n tras generaci\u00f3n, se levantan de madrugada y trabajan duro para poder llevar alimento a todas las mesas mexicanas y m\u00e1s all\u00e1 de nuestro continente\u201d.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Roxana Rubio precis\u00f3 que en Acci\u00f3n Nacional no comprenden por qu\u00e9 no pueden ser permanentes los apoyos a los productores, con fertilizantes y pr\u00e9stamos que puedan pagar y mencion\u00f3 que ahorita la mayor\u00eda trabaja solo para solventar lo que pidieron y lo mismo pasa en todos los gremios.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cLos productores ya est\u00e1n enfadados y es por eso que marcharon el d\u00eda de hoy hace algunas horas, ojal\u00e1 que ya despierte Morena y que los productores abran los ojos y que se den cuenta de que a Morena no le interesa el campo, mucho menos Sinaloa, la muestra est\u00e1 en que cerraron las financieras rurales, es un golpe m\u00e1s para el campo, quitaron todos los apoyos para el campo en este sexenio, Acci\u00f3n Nacional est\u00e1 a favor de que se manifiesten porque solo as\u00ed el gobierno federal los va a voltear a ver\u201d.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">La l\u00edder panista finaliz\u00f3 diciendo que no puede ser posible, que teniendo secretarios de agricultura y los productores con el tiempo encima, no hayan llegado a un acuerdo con los precios. \u201cYa es tiempo de que protejan a este gremio que mantiene en alto el nombre de Sinaloa y de M\u00e9xico\u201d.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Que el gobierno federal invierta en el rescate del campo en vez de estar tirando el dinero en precampa\u00f1as de sus corcholatas: Roxana Rubio &nbsp; La Presidenta del PAN Sinaloa, Roxana Rubio Valdez, declar\u00f3 en conferencia de prensa que urge que el gobierno federal se comprometa con el rescate del campo mexicano, en vez de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4752"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4752\/revisions"}],"predecessor-version":[{"id":27991,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4752\/revisions\/27991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4751"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4752"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}