{"id":4685,"date":"2023-04-11T19:28:36","date_gmt":"2023-04-11T19:28:36","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/11\/multivitaminicos-intravenosos-son-innecesarios-si-se-lleva-una-dieta-equilibrada\/"},"modified":"2025-06-24T22:25:03","modified_gmt":"2025-06-24T22:25:03","slug":"multivitaminicos-intravenosos-son-innecesarios-si-se-lleva-una-dieta-equilibrada","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/11\/multivitaminicos-intravenosos-son-innecesarios-si-se-lleva-una-dieta-equilibrada\/","title":{"rendered":"Multivitam\u00ednicos intravenosos son innecesarios si se lleva una dieta equilibrada"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/2023\/Abril23\/multiit.jpg\" alt=\"multiit\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">La aplicaci\u00f3n de multivitam\u00ednicos v\u00eda intravenosa, o terapia de infusi\u00f3n intravenosa, consiste en la inyecci\u00f3n de diferentes vitaminas, minerales y algunos compuestos como amino\u00e1cidos y antioxidantes, con la finalidad de mejorar el estado de salud, principalmente en aquellas personas que tienen alguna deficiencia en alguno de estos compuestos, inform\u00f3 nutri\u00f3logo de la Facultad de Ciencias de la Nutrici\u00f3n y Gastronom\u00eda (FCNyG) de la Universidad Aut\u00f3noma de Sinaloa (UAS).<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Actualmente, el n\u00famero de personas que utilizan estas terapias va en aumento, argumentando que lo hacen para aumentar la energ\u00eda, fortalecer el sistema inmunol\u00f3gico, mejorar la piel, curar resacas, entre otras, y aunque si bien, estas &nbsp;funcionan, el maestro \u00d3scar Gerardo Figueroa Salcido indic\u00f3 que no se debe abusar su uso, ya que es suficiente con una dieta balanceada para que el cuerpo reciba las vitaminas y minerales necesarios.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cLas personas que suelen promover el uso de las terapias de infusi\u00f3n por multivitam\u00ednicos lo hace con la finalidad de mejorar el estado de salud, pero realmente si una persona lleva una ingesta adecuada de frutas y verduras, como tambi\u00e9n hace ejercicio, o lleva un estilo de vida saludable en su conjunto, realmente no necesita llevar este tipo de terapias\u201d, destac\u00f3.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Asimismo, advirti\u00f3 que los riesgos por consumir este tipo de multivitam\u00ednicos v\u00eda intravenosa van desde excretar las vitaminas o minerales que est\u00e1n inyectando por la innecesidad del cuerpo, hasta reacciones al\u00e9rgicas, e incluso ocasionar insuficiencia renal.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Es por esto que enfatiz\u00f3 que el uso de estas terapias siempre deben ser bajo la supervisi\u00f3n de un profesional de la salud.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cSi alguna persona tiene alguna patolog\u00eda o alguna enfermedad donde tiene alg\u00fan problema en absorber alguna vitamina o mineral, en ese tipo de casos, bajo la indicaci\u00f3n de un profesional de la salud, podr\u00eda ser pertinente o adecuado llevarla; pero de forma general, si la persona no tiene ninguna enfermedad, lleva una dieta equilibrada y balanceada, realmente no es necesario llevar este tipo de terapias\u201d, dijo.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"es-419\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">El especialista recomend\u00f3 a la poblaci\u00f3n siempre informarse y buscar asesor\u00eda de un profesionista antes de malgastar su dinero en productos que posiblemente no tengan efecto o que les puede llevar a alguna complicaci\u00f3n m\u00e9dica.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/p>\n<p class=\"x_MsoNormal\"><span lang=\"es-419\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La aplicaci\u00f3n de multivitam\u00ednicos v\u00eda intravenosa, o terapia de infusi\u00f3n intravenosa, consiste en la inyecci\u00f3n de diferentes vitaminas, minerales y algunos compuestos como amino\u00e1cidos y antioxidantes, con la finalidad de mejorar el estado de salud, principalmente en aquellas personas que tienen alguna deficiencia en alguno de estos compuestos, inform\u00f3 nutri\u00f3logo de la Facultad de Ciencias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4684,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"ppma_author":[31],"class_list":["post-4685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4685"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4685\/revisions"}],"predecessor-version":[{"id":28015,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4685\/revisions\/28015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4684"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4685"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}