{"id":4663,"date":"2023-04-10T20:11:30","date_gmt":"2023-04-10T20:11:30","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/10\/por-definirse-el-precio-del-trigo-rocha\/"},"modified":"2025-06-24T22:25:52","modified_gmt":"2025-06-24T22:25:52","slug":"por-definirse-el-precio-del-trigo-rocha","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/10\/por-definirse-el-precio-del-trigo-rocha\/","title":{"rendered":"Por definirse el precio del trigo: Rocha"},"content":{"rendered":"<div>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/2023\/Abril23\/trigos.jpg\" alt=\"trigos\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Es cuesti\u00f3n de horas para que se defina el precio del trigo, y la propuesta que le plante\u00f3 al presidente Andr\u00e9s Manuel L\u00f3pez Obrador es incluir a Sinaloa en un acuerdo regional junto con los productores de Sonora y los del valle de Mexicali, Baja California, as\u00ed lo inform\u00f3 el gobernador Rub\u00e9n Rocha Moya.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">El mandatario estatal dio a conocer que momentos antes de iniciar su Conferencia, que cada lunes realiza desde el Auditorio de Palacio de Gobierno, se comunic\u00f3 telef\u00f3nicamente con el secretario de Agricultura y Desarrollo Rural, V\u00edctor Manuel Villalobos, quien le inform\u00f3 que ya es cuesti\u00f3n de horas para saber el precio que tendr\u00e1 el trigo, lo cual puede ser este mismo lunes o martes.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Por lo que toca a Sinaloa, la propuesta es incluir la producci\u00f3n local a un acuerdo para el precio que tendr\u00e1 el trigo de Sonora y el del valle de Mexicali, Baja California. \u201cNosotros estamos en la posibilidad de incorporarnos en el acuerdo global que se tenga para el trigo en general, para el trigo de Sonora y del valle de Mexicali, \u00e9se pudiera darnos un aliento, as\u00ed se lo plante\u00e9 yo al presidente \u2013L\u00f3pez Obrador-, que a nosotros se nos incorpore en lo que beneficie por supuesto a nuestro trigo. Entonces, estamos esperando, ahorita me dec\u00eda el secretario de Agricultura, el doctor V\u00edctor Villalobos que ya le hizo una propuesta al presidente y que estar\u00eda esperando de hoy a ma\u00f1ana que le d\u00e9 respuesta, vamos a ver qu\u00e9 hay al respecto\u201d, explic\u00f3.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">En cuanto al caso del ma\u00edz, el gobernador Rocha inform\u00f3 que ya se tuvo el acercamiento con las autoridades federales para la compra del mill\u00f3n de toneladas por parte de Segalmex, compromiso hecho por el presidente de M\u00e9xico a petici\u00f3n del mismo gobernador, las cuales se pagar\u00e1n con el precio de garant\u00eda fijado en el Programa del Bienestar, que es de 6 mil 965 pesos por tonelada.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Adelant\u00f3 que este mismo lunes sostendr\u00e1 una reuni\u00f3n con los productores agr\u00edcolas para analizar los t\u00e9rminos y condiciones de este retiro del mill\u00f3n de toneladas del mercado, tal como lo propusieron las mismas organizaciones y que \u00e9l mismo le propuso al presidente L\u00f3pez Obrador durante su visita a Culiac\u00e1n.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cYa incluso se tuvo una reuni\u00f3n con Hacienda, donde estuvo el secretario de Finanzas nuestro para efecto de que se garantice el recurso, eso es muy importante para que no quede al vuelo, sino que quede preciso y se empiece a operar el contrato de compra y decir qui\u00e9nes van a estar vendiendo, que se supone que es parejo para todos, pero vamos a ver, eso lo vamos a platicar ahora mismo con los productores para hac\u00e9rselo saber a Segalmex, que para la semana que entra ya tendr\u00e1 instalado en Sinaloa un operativo que le permitir\u00e1 hacer las operaciones de compra\u201d, concluy\u00f3.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/p>\n<\/div>\n<div><br aria-hidden=\"true\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es cuesti\u00f3n de horas para que se defina el precio del trigo, y la propuesta que le plante\u00f3 al presidente Andr\u00e9s Manuel L\u00f3pez Obrador es incluir a Sinaloa en un acuerdo regional junto con los productores de Sonora y los del valle de Mexicali, Baja California, as\u00ed lo inform\u00f3 el gobernador Rub\u00e9n Rocha Moya. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4662,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4663"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4663\/revisions"}],"predecessor-version":[{"id":28026,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4663\/revisions\/28026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4662"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4663"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}