{"id":4633,"date":"2023-04-04T00:15:01","date_gmt":"2023-04-04T00:15:01","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/04\/amlo-dio-respuesta-positiva-a-la-propuesta-de-rocha-para-la-comercializacion-del-maiz\/"},"modified":"2025-06-24T22:25:53","modified_gmt":"2025-06-24T22:25:53","slug":"amlo-dio-respuesta-positiva-a-la-propuesta-de-rocha-para-la-comercializacion-del-maiz","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/04\/04\/amlo-dio-respuesta-positiva-a-la-propuesta-de-rocha-para-la-comercializacion-del-maiz\/","title":{"rendered":"AMLO dio respuesta positiva a la propuesta de Rocha para la comercializaci\u00f3n del ma\u00edz"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/2023\/mar23\/mai\u0301zzz.jpg\" alt=\"mai\u0301zzz\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">El gobernador Rub\u00e9n Rocha Moya inform\u00f3 que encontr\u00f3 respuesta positiva a las peticiones que le hizo al presidente de la Rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador, para la comercializaci\u00f3n del ma\u00edz, algunas que las hizo de manera p\u00fablica durante su mensaje, como la compra de un mill\u00f3n de toneladas por parte de Segalmex, y otras de manera directa que le dijo en privado, como fue una contrapuesta del presidente respecto a la exportaci\u00f3n de ma\u00edz a partir de junio, una vez que venza el impedimento para ello, para que en lugar de que sea exportado el volumen excedente, tambi\u00e9n sea adquirido por Segalmex como reserva.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">As\u00ed lo explic\u00f3 el propio gobernador Rocha durante su Conferencia Semanera, al se\u00f1alar que durante la visita que hizo el presidente este s\u00e1bado a Sinaloa, le plante\u00f3 no s\u00f3lo el caso de la comercializaci\u00f3n del ma\u00edz, de cual recibi\u00f3 respuesta inmediata, sino tambi\u00e9n el tema del trigo, para el que tendr\u00e1 una respuesta para este mi\u00e9rcoles, cuyos productores demandan un precio de 8 mil pesos por tonelada.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">El mandatario estatal mostr\u00f3 en su Conferencia los posicionamientos que publicaron el s\u00e1bado la CAADES y otro firmado por varios dirigentes del sector social, los cuales se los plante\u00f3 directamente al presidente L\u00f3pez Obrador.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Respecto a la primera de las propuestas, de que Segalmex compre un mill\u00f3n de toneladas, al precio de garant\u00eda de 6 mil 965 pesos, se\u00f1al\u00f3 que encontr\u00f3 una inmediata respuesta. \u201cEs muy importante anunciar que se van a comprar anticipadamente, desde ahora, el presidente me dijo: t\u00fa dalo conocer el lunes, que vamos a comprar un mill\u00f3n de toneladas, y esto tiene un impacto, pues se van a sacar un mill\u00f3n de toneladas del volumen general, y el otro impacto es que se comprar\u00e1n a 6 mil 965 pesos, que es el precio de garant\u00eda para el Bienestar y se extiende para los productores de mediana capacidad, hasta 50 hect\u00e1reas y hasta 600 toneladas\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">En cuanto a la segunda propuesta, de que se permitiera exportar el volumen excedente, a partir de junio una vez que venza el impedimento acordado por el Gobierno Federal, el gobernador Rocha recibi\u00f3 de parte del presidente L\u00f3pez Obrador una contrapropuesta, igualmente positiva, que se refiere a la posibilidad de comprar ese volumen excedente tambi\u00e9n por parte de Segalmex, pero esto se acordar\u00e1 en junio.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201c\u00bfQu\u00e9 me dijo el presidente? Esto no lo respondi\u00f3 en p\u00fablico pero en privado me lo dijo: yo quisiera que en efecto no se exporte nada a partir de junio, quisiera que si hay excedente mejor pensemos en que se compre como reserva, pero eso se ver\u00eda en junio\u201d, explic\u00f3 el gobernador Rocha, al mencionar que esto fue la respuesta que le dio el presidente, por lo que no habr\u00eda necesidad de exportar el ma\u00edz excedente.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">La tercera propuesta que le hizo a L\u00f3pez Obrador tambi\u00e9n encontr\u00f3 una r\u00e1pida respuesta positiva, y \u00e9sta consiste en que no se permita la importaci\u00f3n de ma\u00edz blanco proveniente de Sud\u00e1frica mientras dura el proceso de comercializaci\u00f3n del ma\u00edz de Sinaloa. Cabe destacar que el propio presidente de M\u00e9xico rechaz\u00f3 esta posibilidad, ya que el ma\u00edz de Sud\u00e1frica es transg\u00e9nico. \u201cEl presidente mismo me lo dijo en el avi\u00f3n, cuando \u00edbamos viajando a Mazatl\u00e1n, no vamos a importar ma\u00edz blanco de Sud\u00e1frica porque es adem\u00e1s transg\u00e9nico\u201d, precis\u00f3.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Respecto al tema de la comercializaci\u00f3n del trigo, el mandatario estatal dijo que la respuesta que le dio es que ser\u00e1 en esta misma semana, el mi\u00e9rcoles, cuando se determine el precio que tendr\u00e1, lo cual le ser\u00e1 informado por el secretario de Agricultura, V\u00edctor Manuel Villalobos.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201c\u00c9l me va a hablar el mi\u00e9rcoles para decirme en qu\u00e9 t\u00e9rminos est\u00e1n tratando y ver justamente qu\u00e9 tanto es posible llegar a los ocho mil pesos por tonelada o si hay alg\u00fan planteamiento adicional. De cualquier manera este tema del trigo est\u00e1 suficientemente tratado y les voy a dar respuesta a los trigueros de aqu\u00ed al mi\u00e9rcoles o jueves, que tengamos ya una mayor precisi\u00f3n\u201d, concluy\u00f3.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"x_gmail-MsoNoSpacing\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Aqu\u00ed precis\u00f3 que el secretario Villalobos le coment\u00f3 que existe una situaci\u00f3n especial, pues Segalmex no compra trigo, pero la indicaci\u00f3n que recibi\u00f3 del presidente L\u00f3pez Obrador es que pudieran hacer una excepci\u00f3n. \u201cEntonces la modalidad la vamos a conocer el mi\u00e9rcoles y a los trigueros del Carrizo les digo que no se desesperen, ya que no tienen claridad en el precio, pero yo estoy muy pendiente de ello\u201d, concluy\u00f3.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Rub\u00e9n Rocha Moya inform\u00f3 que encontr\u00f3 respuesta positiva a las peticiones que le hizo al presidente de la Rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador, para la comercializaci\u00f3n del ma\u00edz, algunas que las hizo de manera p\u00fablica durante su mensaje, como la compra de un mill\u00f3n de toneladas por parte de Segalmex, y otras de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4633"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4633\/revisions"}],"predecessor-version":[{"id":28038,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4633\/revisions\/28038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4632"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4633"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}