{"id":4538,"date":"2023-03-28T14:56:25","date_gmt":"2023-03-28T14:56:25","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/28\/ayuntamiento-continua-mejorando-la-ciudad-con-el-sistema-de-pavimentacion-con-concreto-hidraulico\/"},"modified":"2025-06-24T22:25:57","modified_gmt":"2025-06-24T22:25:57","slug":"ayuntamiento-continua-mejorando-la-ciudad-con-el-sistema-de-pavimentacion-con-concreto-hidraulico","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/28\/ayuntamiento-continua-mejorando-la-ciudad-con-el-sistema-de-pavimentacion-con-concreto-hidraulico\/","title":{"rendered":"Ayuntamiento contin\u00faa mejorando la ciudad con el sistema de pavimentaci\u00f3n con concreto hidr\u00e1ulico"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/2023\/mar23\/mejayun.jpg\" alt=\"mejayun\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Las obras p\u00fablicas para mejorar las vialidades de Culiac\u00e1n contin\u00faan por parte del Ayuntamiento, y es que el sistema de pavimentaci\u00f3n con concreto hidr\u00e1ulico ha llegado a diversos sectores de la capital.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>En esta ocasi\u00f3n toc\u00f3 turno a cuatro zonas en las que las cuadrillas de la Secretar\u00eda de Obras y Servicios P\u00fablicos, ya tienen un avance considerable del proyecto, sistema realizado con un material de alta calidad y mayor durabilidad, por lo que automovilistas y peatones tendr\u00e1n calles m\u00e1s dignas para transitar.<br aria-hidden=\"true\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><br aria-hidden=\"true\" \/>Las colonias beneficiadas son:<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>\u2022 Calle Mina de Guadalupe de los Reyes, tramo entre Prolongaci\u00f3n \u00c1lvaro Obreg\u00f3n y calle Plutarco El\u00edas Calles, colonia Francisco I. Madero, ah\u00ed se trabaja en red de agua potable.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>\u2022 Calle Carlos Mar\u00eda Esquerro, tramo entre Av. Aar\u00f3n Irizar L\u00f3pez y Feliciano Garc\u00eda, colonia Adolfo L\u00f3pez Mateos, se labora en corte de caja para continuar con las terracer\u00edas.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>\u2022 Calle Mina Mazonique, entre Av. 21 de Marzo y Av. Jos\u00e9 L\u00f3pez Portillo en colonia Toledo Corro, ya se registra el colado de guarniciones y losas de concreto.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>\u2022 En lo que respecta a la vialidad Primavera entre Prol. \u00c1lvaro Obreg\u00f3n y Av. Huizaches en la colonia Jes\u00fas Manuel Camez Valdez,<br aria-hidden=\"true\" \/>los vecinos ya disfrutan de la obra concluida.<br aria-hidden=\"true\" \/><\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><br aria-hidden=\"true\" \/>La actual administraci\u00f3n dio a conocer que arribar\u00e1n a las colonias que requieren m\u00e1s atenci\u00f3n, todo ello, con la finalidad de que las familias culiacanenses puedan trasladarse de manera \u00f3ptima sobre todo en temporada de lluvias.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Las obras p\u00fablicas para mejorar las vialidades de Culiac\u00e1n contin\u00faan por parte del Ayuntamiento, y es que el sistema de pavimentaci\u00f3n con concreto hidr\u00e1ulico ha llegado a diversos sectores de la capital. En esta ocasi\u00f3n toc\u00f3 turno a cuatro zonas en las que las cuadrillas de la Secretar\u00eda de Obras y Servicios P\u00fablicos, ya [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"ppma_author":[31],"class_list":["post-4538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4538"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4538\/revisions"}],"predecessor-version":[{"id":28073,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4538\/revisions\/28073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4537"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4538"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}