{"id":4516,"date":"2023-03-24T04:10:38","date_gmt":"2023-03-24T04:10:38","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/24\/el-grupo-las-sombras-de-culiacan-gana-el-concurso-triunfado-macizo-por-culiacan\/"},"modified":"2025-06-24T22:25:58","modified_gmt":"2025-06-24T22:25:58","slug":"el-grupo-las-sombras-de-culiacan-gana-el-concurso-triunfado-macizo-por-culiacan","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/24\/el-grupo-las-sombras-de-culiacan-gana-el-concurso-triunfado-macizo-por-culiacan\/","title":{"rendered":"El grupo Las Sombras de Culiac\u00e1n gana el concurso Triunfado Macizo por Culiac\u00e1n"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/ene23\/sombras.jpg\" alt=\"sombras\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Una gran fiesta y alegr\u00eda fue la que se vivi\u00f3 esta tarde en la gran final de \u00abTriunfando Macizo por Culiac\u00e1n\u00bb, concurso de canto organizado por el Instituto Municipal de Cultura Culiac\u00e1n y la estaci\u00f3n de radio La Bestia 102.5 F.M.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Fueron cinco talentos los que lograron llegar hasta la \u00faltima ronda, compitiendo cada jueves en las categor\u00edas de campirano, norte\u00f1o, solista y sierre\u00f1o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>La gran final estuvo muy re\u00f1ida, sin embargo, s\u00f3lo un grupo o artista deb\u00eda llevarse las palmas de oro, resultando como ganadores: Las Sombras de Culiac\u00e1n, quienes deleitaron al p\u00fablico conocedor con las melod\u00edas \u00abLos barandales del puente\u00bb y \u00abEl solterito\u00bb, una cumbia que fue \u00e9xito de Los Canelos de Durango, logrando acaparar la atenci\u00f3n de los jueces y poniendo a bailar a la audiencia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Las porras y los aplausos de las familias y amigos no dejaban de hacerse presentes para apoyar a su artista favorito, pues tambi\u00e9n estuvieron en la contienda de talentos: Carmen Camacho, Grupo Semejante y Pablo Baz\u00e1n, pero en esta primera edici\u00f3n del concurso no se vieron beneficiados.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Tras ello, el director del IMCC, Alonso Ram\u00edrez Reyes, destac\u00f3 que los concursantes que no conquistaron este primer encuentro, siempre tendr\u00e1n las puertas abiertas del Instituto, asimismo, agradeci\u00f3 a los presentes por la asistencia, tambi\u00e9n al alcalde Juan de Dios G\u00e1mez Mend\u00edvil por el apoyo brindado para poder cristalizar proyectos de esta \u00edndole, pues el objetivo es tener una convivencia familiar y apoyar a los artistas que tiene Culiac\u00e1n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Finalmente, Ram\u00edrez Reyes hizo entrega de reconocimientos a los jueces que tuvieron una tarea dif\u00edcil durante el proceso de elecci\u00f3n, Manuel Parra Arag\u00f3n, Rafael Gonz\u00e1lez Romero, Ren\u00e9 Bastidas Lomas, y para sorpresa de todos se reconoci\u00f3 a Mauricio \u00abG\u00fcicho\u00bb Romero, fundador de Los Intocables del Norte.<br aria-hidden=\"true\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><br aria-hidden=\"true\" \/>Las Sombras de Culiac\u00e1n fueron acreedores a los premios de grabaci\u00f3n de tres canciones en estudio profesional, la filmaci\u00f3n de un video musical, realizar una gira de difusi\u00f3n en medios de comunicaci\u00f3n, un juego de vestimenta confeccionado por \u2018Trajes Culiac\u00e1n\u2019 y la proyecci\u00f3n de su material en la radio durante dos meses.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una gran fiesta y alegr\u00eda fue la que se vivi\u00f3 esta tarde en la gran final de \u00abTriunfando Macizo por Culiac\u00e1n\u00bb, concurso de canto organizado por el Instituto Municipal de Cultura Culiac\u00e1n y la estaci\u00f3n de radio La Bestia 102.5 F.M. Fueron cinco talentos los que lograron llegar hasta la \u00faltima ronda, compitiendo cada jueves [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4515,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"ppma_author":[31],"class_list":["post-4516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4516"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4516\/revisions"}],"predecessor-version":[{"id":28081,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4516\/revisions\/28081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4515"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4516"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}