{"id":4482,"date":"2023-03-22T14:26:58","date_gmt":"2023-03-22T14:26:58","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/22\/inicia-la-auditoria-externa-de-recertificacion-al-sistema-de-gestion-de-la-calidad\/"},"modified":"2025-06-24T22:25:59","modified_gmt":"2025-06-24T22:25:59","slug":"inicia-la-auditoria-externa-de-recertificacion-al-sistema-de-gestion-de-la-calidad","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/22\/inicia-la-auditoria-externa-de-recertificacion-al-sistema-de-gestion-de-la-calidad\/","title":{"rendered":"Inicia la Auditor\u00eda Externa de Recertificaci\u00f3n al Sistema de Gesti\u00f3n de la Calidad"},"content":{"rendered":"<div style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">&nbsp;<img decoding=\"async\" src=\"images\/2022\/2023\/2023\/mar23\/reuuas.jpg\" alt=\"reuuas\" style=\"display: block; margin: 20px auto;\" \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Del 21 al 30 de marzo de 2023, la Universidad Aut\u00f3noma de Sinaloa (UAS) estar\u00e1 siendo auditada por el Organismo de Certificaci\u00f3n ACCM Am\u00e9rica con fines de recertificaci\u00f3n a 48 procesos que renovar\u00e1n y ampliar\u00e1n su alcance en el Sistema de Gesti\u00f3n de la Calidad (SGC) por un nuevo periodo 2023-2026, conforme a la Norma de Referencia ISO 9001:2015.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">La reuni\u00f3n de apertura a esta Auditor\u00eda Externa de Recertificaci\u00f3n al Sistema de Gesti\u00f3n de la Calidad cont\u00f3 con la presencia de los miembros del equipo auditor de ACCM Am\u00e9rica, titulares, responsables de procesos y personal operativo de las unidades organizacionales y acad\u00e9micas que conforman el alcance del SGC de la UAS, as\u00ed como de la directora de Auditor\u00eda Interna y representante del rector, doctor Jes\u00fas Madue\u00f1a Molina, la doctora Marifeli Avenda\u00f1o Corrales; el director del Sistema de Gesti\u00f3n de la Calidad, maestro en ciencias Omar Armando Beltr\u00e1n Zazueta y el Auditor L\u00edder, ingeniero Luis Roberto Sierra Ortiz, director ejecutivo del Organismo de Certificaci\u00f3n.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cEstos ejercicios son muy importantes porque con ellos, por un lado, demostramos la rendici\u00f3n de cuentas en cada una de las cosas que hace la instituci\u00f3n, pero tambi\u00e9n, buscamos esa mejora continua todos los d\u00edas\u201d, dijo la directora de Auditor\u00eda Interna.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">A su vez, el director del Sistema de Gesti\u00f3n de la Calidad, Omar Armando Beltr\u00e1n Zazueta, destac\u00f3 que el presente ejercicio de evaluaci\u00f3n de la conformidad y del cumplimiento de los requisitos aplicables de los diferentes productos y servicios que se otorgan para satisfacer a los usuarios y partes interesadas de nuestra instituci\u00f3n, responde a las metas y objetivos trazados en el Eje estrat\u00e9gico IV del Plan de Desarrollo Institucional Con Visi\u00f3n de Futuro 2025 que encabeza el rector, en la b\u00fasqueda de consolidar el SGC y cumplir con las expectativas de los usuarios.&nbsp;<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cEl mantenimiento y la consolidaci\u00f3n del Sistema de Gesti\u00f3n de la Calidad conlleva compromiso y responsabilidad de todos sus participantes; por ello, para la Direcci\u00f3n del Sistema de Gesti\u00f3n de la Calidad es fundamental agradecer y reconocer la labor que realizan de manera permanente los titulares de las unidades organizacionales y acad\u00e9micas, as\u00ed como los responsables de los procesos y colaboradores de los mismos para la mejora de nuestro Sistema de Gesti\u00f3n, expuso.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Para terminar, el Auditor L\u00edder del Organismo de Certificaci\u00f3n ACCM Am\u00e9rica, agradeci\u00f3 a la Universidad por permitirles ser el organismo evaluador y certificador del SGC \u201ccon los valores de integridad, transparencia y confianza que ostentamos como organismo de certificaci\u00f3n, siendo la satisfacci\u00f3n de nuestros usuarios los m\u00e1s importante para nosotros\u201d.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Cabe se\u00f1alar que la Auditor\u00eda Externa de Recertificaci\u00f3n al Sistema de Gesti\u00f3n de la Calidad da conclusi\u00f3n a los trabajos realizados en la Jornada de Evaluaci\u00f3n a la Conformidad del Sistema de Gesti\u00f3n de la Calidad (SGC) 2023 que iniciaron el pasado 13 de febrero del a\u00f1o en curso.<\/span><\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Del 21 al 30 de marzo de 2023, la Universidad Aut\u00f3noma de Sinaloa (UAS) estar\u00e1 siendo auditada por el Organismo de Certificaci\u00f3n ACCM Am\u00e9rica con fines de recertificaci\u00f3n a 48 procesos que renovar\u00e1n y ampliar\u00e1n su alcance en el Sistema de Gesti\u00f3n de la Calidad (SGC) por un nuevo periodo 2023-2026, conforme a la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4482"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4482\/revisions"}],"predecessor-version":[{"id":28094,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4482\/revisions\/28094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4481"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4482"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}