{"id":4451,"date":"2023-03-16T05:42:35","date_gmt":"2023-03-16T05:42:35","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/16\/preocupa-confrontacion-entre-la-uas-y-el-congreso-del-estado-de-sinaloa\/"},"modified":"2025-06-24T22:26:01","modified_gmt":"2025-06-24T22:26:01","slug":"preocupa-confrontacion-entre-la-uas-y-el-congreso-del-estado-de-sinaloa","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/16\/preocupa-confrontacion-entre-la-uas-y-el-congreso-del-estado-de-sinaloa\/","title":{"rendered":"Preocupa confrontaci\u00f3n entre la UAS y el Congreso del Estado de Sinaloa"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/2023\/mar23\/PRDS.jpg\" alt=\"PRDS\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">La Ley de Educaci\u00f3n Superior en el estado de Sinaloa debe ser armonizada desde gobierno del estado con un di\u00e1logo abierto entre el Congreso, gobierno y la propia universidad toda vez que las confrontaciones pueden subir de nivel y llevar a un caos de violencia, consider\u00f3 el presidente del Partido de la Revoluci\u00f3n Democr\u00e1tica en la entidad, Oner Lazcano L\u00f3pez.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Acompa\u00f1ado por el secretrio de Comunicaci\u00f3n de dicho partido pol\u00edtico, Humberto Dom\u00ednguez Betancourt, invit\u00f3 al gobernador del Estado Rub\u00e9n Rocha Moya y al propio rector de la m\u00e1xima casa de estudios Jes\u00fas Madue\u00f1a Molina a que se sienten a dialogar y establezcan una mesa de di\u00e1logo para corregir y salvar las diferencias que hoy en d\u00eda se tienen por el bien de los universitarios.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Lazcano L\u00f3pez, dej\u00f3 en claro que \u00abdebe ser la Universidad Aut\u00f3noma de Sinaloa quien maneje y controle la instituci\u00f3n educativa lejos de que, sea el partido de Morena quien quiera entrometerse a esta, de igual modo el Congreso del Estado o gobierno estatal quienes son los insistentes en cambiar la Ley de Educaci\u00f3n Superior con clausulas que afectan claramente a la UAS\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Por \u00fatimo, el secretario de comunicaci\u00f3n del PRD, Dom\u00ednguez Betancourt, puntualiz\u00f3 que la universidad por todos los logros que ha tenido en los \u00faltimos a\u00f1os y el reconocimiento que tiene a nivel nacional y los convenios con universidades extranjeras, y otros muchos m\u00e1s reconocimientos ser\u00e1 defendida por el pueblo y todos los ciudadanos Sinaloenses que acudir\u00e1n en defensa de su Alma M\u00e1ter.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/CELINA FONSECA.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Ley de Educaci\u00f3n Superior en el estado de Sinaloa debe ser armonizada desde gobierno del estado con un di\u00e1logo abierto entre el Congreso, gobierno y la propia universidad toda vez que las confrontaciones pueden subir de nivel y llevar a un caos de violencia, consider\u00f3 el presidente del Partido de la Revoluci\u00f3n Democr\u00e1tica en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4451"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4451\/revisions"}],"predecessor-version":[{"id":28104,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4451\/revisions\/28104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4450"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4451"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}