{"id":4447,"date":"2023-03-16T03:33:07","date_gmt":"2023-03-16T03:33:07","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/16\/ventanilla-para-programa-de-motores-marinos-cierra-el-31-de-marzo-secretaria-de-pesca\/"},"modified":"2025-06-24T22:26:01","modified_gmt":"2025-06-24T22:26:01","slug":"ventanilla-para-programa-de-motores-marinos-cierra-el-31-de-marzo-secretaria-de-pesca","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/16\/ventanilla-para-programa-de-motores-marinos-cierra-el-31-de-marzo-secretaria-de-pesca\/","title":{"rendered":"Ventanilla para programa de motores marinos cierra el 31 de marzo: Secretar\u00eda de Pesca"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/2023\/mar23\/motors.jpg\" alt=\"motors\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Como parte del compromiso del Gobernador Rub\u00e9n Rocha Moya para otorgar atenci\u00f3n prioritaria a los sectores sociales m\u00e1s vulnerables, la Secretar\u00eda de Pesca y Acuacultura que encabeza Flor Emilia Guerra Mena, se\u00f1al\u00f3 que a\u00fan est\u00e1 abierta la ventanilla para la recepci\u00f3n de documentos para el programa de motores marinos, por lo que exhort\u00f3 a los interesados a acudir de inmediato a presentar su solicitud.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Guerra Mena precis\u00f3 que este programa es el m\u00e1s solicitado por el sector e inici\u00f3 desde el pasado 06 de marzo, recordando que esta convocatoria estar\u00e1 vigente solamente hasta el d\u00eda \u00faltimo de este mes.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u00abEs un recurso de 50 millones, estamos calculando m\u00e1s o menos 500 motores, dependiendo del caballaje y como est\u00e9n las solicitudes. Obviamente si las solicitudes son de m\u00e1s de 60 caballos para arriba, es un motor much\u00edsimo m\u00e1s caro y las presas, los acuacultores, los del sur, solicitan motores peque\u00f1os de 5, 15 o 25 caballos y esos son m\u00e1s baratos\u00bb, agreg\u00f3 la Secretaria.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Por otra parte, destac\u00f3 el \u00e9xito del Programa Estatal de Inspecci\u00f3n y Vigilancia Pesquera, implementado con recursos estatales en su totalidad como apoyo al sector pesquero local, ya que est\u00e1 facultad es responsabilidad federal.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u00abSon 14 millones este a\u00f1o, cerramos ventanilla exitosamente con m\u00e1s solicitudes que el a\u00f1o pasado. El a\u00f1o pasado tuvimos 57, hoy 63, tenemos 6 m\u00e1s y eso es muy bueno, aunque haya m\u00e1s dinero, lo importante es la participaci\u00f3n del sector pesquero que le urge y s\u00ed est\u00e1 siendo emp\u00e1tico con Gobierno del Estado en este tema. Cerramos ventanillas, ya estamos en la preparaci\u00f3n para decidir de qu\u00e9 manera, a qui\u00e9nes y cu\u00e1nto toca a cada organizaci\u00f3n y aqu\u00ed en el centro fue donde m\u00e1s solicitudes se recibieron\u00bb, expres\u00f3 la titular de Pesca.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Finalmente, la Secretaria coment\u00f3 que de manera permanente est\u00e1n realizando labores de ordenamiento pesquero con el objetivo de construir un padr\u00f3n \u00fanico estatal que permita una coordinaci\u00f3n m\u00e1s estrecha con la autoridad federal del sector para lo relativo a los programas que benefician a los pescadores.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte del compromiso del Gobernador Rub\u00e9n Rocha Moya para otorgar atenci\u00f3n prioritaria a los sectores sociales m\u00e1s vulnerables, la Secretar\u00eda de Pesca y Acuacultura que encabeza Flor Emilia Guerra Mena, se\u00f1al\u00f3 que a\u00fan est\u00e1 abierta la ventanilla para la recepci\u00f3n de documentos para el programa de motores marinos, por lo que exhort\u00f3 a los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4447"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4447\/revisions"}],"predecessor-version":[{"id":28106,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4447\/revisions\/28106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4446"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4447"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}