{"id":4379,"date":"2023-03-09T13:21:10","date_gmt":"2023-03-09T13:21:10","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/09\/atiende-la-uas-el-compromiso-de-cobertura-universal-al-ofrecer-16-mil-430-fichas-adicionales\/"},"modified":"2025-06-24T22:26:04","modified_gmt":"2025-06-24T22:26:04","slug":"atiende-la-uas-el-compromiso-de-cobertura-universal-al-ofrecer-16-mil-430-fichas-adicionales","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/03\/09\/atiende-la-uas-el-compromiso-de-cobertura-universal-al-ofrecer-16-mil-430-fichas-adicionales\/","title":{"rendered":"Atiende la UAS el compromiso de cobertura universal al ofrecer 16 mil 430 fichas adicionales"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/2023\/mar23\/cobertura.jpg\" alt=\"cobertura\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><span lang=\"ES\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Por acuerdo de la Comisi\u00f3n Institucional de Admisi\u00f3n y en atenci\u00f3n al compromiso de cobertura universal, la Universidad Aut\u00f3noma de Sinaloa (UAS), ofrecer\u00e1 16 mil 430 fichas adicionales para los niveles medio superior y superior el pr\u00f3ximo lunes 13 de marzo, fecha en que abrir\u00e1 el portal de preinscripciones en punto de las 8:00 horas, anunci\u00f3 el Rector, doctor Jes\u00fas Madue\u00f1a Molina.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Explic\u00f3 que durante el recorrido por diferentes unidades acad\u00e9micas de todo el estado se detect\u00f3 la solicitud de los padres de familia de que sus hijos no alcanzaron una ficha en alguna preparatoria o carrera.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cHoy anunciamos para que est\u00e9n atentos porque el lunes a las 8 de la ma\u00f1ana puedan obtener su ficha (\u2026) todo aquel que toque las puertas de la UAS tendr\u00e1 la oportunidad de estudiar en ella\u201d, expres\u00f3 el Rector, al precisar que las fichas que se ofertar\u00e1n ser\u00e1n para las escuelas que se quedaron sin fichas en la primera entrega porque se saturaron.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Para el Nivel Bachillerato se ofertar\u00e1n 4 mil 400 nuevas fichas en las preparatorias CU Mochis, Mochis, Ruiz Cortines Extensi\u00f3n Batamote en la Unidad Regional Norte; en la Unidad Regional Centro Norte en las prepas Angostura, Guasave Diurna y Guasave Nocturna; en la Unidad Regional Centro La Cruz, Navolato, Augusto C\u00e9sar Sandino, Central Diurna, Central Nocturna, Dr. Salvador Allende y su Extensi\u00f3n Marcelo Loya, Emiliano Zapata, Hermanos Flores Mag\u00f3n, Rafael Buelna Tenorio, Victoria del Pueblo y en la Unidad Regional Sur se abrir\u00e1n fichas en la Mazatl\u00e1n con su Extensi\u00f3n Rosales, y Jaramillo con su Extensi\u00f3n.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">En el Nivel Superior se abrir\u00e1n 12 mil 30 nuevas fichas en carreras como Medicina y sus extensiones Mochis, Mazatl\u00e1n y Guasave, Enfermer\u00eda y Agricultura Valle del Fuerte, Agricultura Valle del Carrizo, Ingenier\u00eda, Psicolog\u00eda, Qu\u00edmica, Biolog\u00eda, Odontolog\u00eda, Nutrici\u00f3n y Gastronom\u00eda, CIDOCS, Agronom\u00eda, Mecatr\u00f3nica, Veterinaria, Arquitectura, Inform\u00e1tica, Ingenier\u00eda, Educaci\u00f3n F\u00edsica y Deporte, Dise\u00f1o y Artes, Trabajo Social, Ciencias de la Tierra, Criminal\u00edstica, FCA Culiac\u00e1n y Navolato, Psicolog\u00eda, Idiomas, Artes Visuales y Estudios Internacionales, Derecho, Arquitectura, Educaci\u00f3n, y FACEAM.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cEn total vamos a poner a consideraci\u00f3n 16 mil 430 fichas a partir del lunes 13 de marzo a las 8 de la ma\u00f1ana (\u2026) para la carrera de M\u00e9dico General se van a ofertar 600, de ellas 300 en Culiac\u00e1n, 100 en Mochis, 100 Mazatl\u00e1n y 100 en Guasave\u201d, precis\u00f3 el Rector.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Los aspirantes que ya tienen una ficha de la primera remesa tienen como l\u00edmite para terminar su proceso de preinscripci\u00f3n el 10 de marzo para los de bachillerato y el 17 de marzo para licenciatura, quien no culmine el proceso se le cancelar\u00e1 su ficha; las nuevas fichas tendr\u00e1n como vencimiento el 17 de marzo, por lo que el Rector exhort\u00f3 a los j\u00f3venes a cumplir con todos los pasos indicados en la p\u00e1gina para que puedan aplicar el examen de admisi\u00f3n.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Indic\u00f3 que de las 26 mil fichas que se pusieron a disposici\u00f3n en la primera etapa ya se adjudicaron 21 mil 408, hay a\u00fan 5 mil 208 disponibles, pero se ubican en el \u00e1rea rural, mientras que en el Nivel Superior se ofertaron en un primer momento 30 mil 710 fichas de las cuales se adjudicaron 24 mil 474.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por acuerdo de la Comisi\u00f3n Institucional de Admisi\u00f3n y en atenci\u00f3n al compromiso de cobertura universal, la Universidad Aut\u00f3noma de Sinaloa (UAS), ofrecer\u00e1 16 mil 430 fichas adicionales para los niveles medio superior y superior el pr\u00f3ximo lunes 13 de marzo, fecha en que abrir\u00e1 el portal de preinscripciones en punto de las 8:00 horas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4379"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4379\/revisions"}],"predecessor-version":[{"id":28130,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4379\/revisions\/28130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4378"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4379"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}