{"id":42152,"date":"2026-05-13T13:51:45","date_gmt":"2026-05-13T20:51:45","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/?p=42152"},"modified":"2026-05-13T13:51:45","modified_gmt":"2026-05-13T20:51:45","slug":"yeraldine-bonilla-desmiente-rumores-sobre-presencia-del-gobernador-en-palacio","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2026\/05\/13\/yeraldine-bonilla-desmiente-rumores-sobre-presencia-del-gobernador-en-palacio\/","title":{"rendered":"Yeraldine Bonilla desmiente rumores sobre presencia del gobernador en Palacio"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2026\/05\/img_9187-300x225.jpg\" class=\"wp-image-42150\" srcset=\"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2026\/05\/img_9187-300x225.jpg 300w, https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2026\/05\/img_9187.jpg 755w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p class=\"p2\">Culiac\u00e1n, Sinaloa; 13 de mayo de 2026.- La gobernadora interina de Sinaloa, Yeraldine Bonilla Valverde desminti\u00f3 las versiones que se\u00f1alaban que el gobernador con licencia se encontraba en Palacio de Gobierno y aclar\u00f3 que permanece en su casa y en buen estado de salud.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>REDACCI\u00d3N\/CELINA FONSECA. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culiac\u00e1n, Sinaloa; 13 de mayo de 2026.- La gobernadora interina de Sinaloa, Yeraldine Bonilla Valverde desminti\u00f3 las versiones que se\u00f1alaban que el gobernador con licencia se encontraba en Palacio de Gobierno y aclar\u00f3 que permanece en su casa y en buen estado de salud. REDACCI\u00d3N\/CELINA FONSECA.<\/p>\n","protected":false},"author":11,"featured_media":42151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,14],"tags":[],"ppma_author":[42],"class_list":["post-42152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes","category-seguridad"],"aioseo_notices":[],"authors":[{"term_id":42,"user_id":11,"is_guest":0,"slug":"celinavision","display_name":"Redacci\u00f3n Vision Ciudadana","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5974f79b452df50dc11600a3c0f261022fc34eb0879d83b503e86107cd3e64cc?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/42152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=42152"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/42152\/revisions"}],"predecessor-version":[{"id":42153,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/42152\/revisions\/42153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/42151"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=42152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=42152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=42152"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=42152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}