{"id":4157,"date":"2023-02-23T03:56:51","date_gmt":"2023-02-23T03:56:51","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/02\/23\/la-uas-muestra-en-la-expo-agro-sinaloa-2023-su-calidad-en-innovacion-e-investigacion\/"},"modified":"2025-06-24T22:26:14","modified_gmt":"2025-06-24T22:26:14","slug":"la-uas-muestra-en-la-expo-agro-sinaloa-2023-su-calidad-en-innovacion-e-investigacion","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/02\/23\/la-uas-muestra-en-la-expo-agro-sinaloa-2023-su-calidad-en-innovacion-e-investigacion\/","title":{"rendered":"La UAS muestra en la Expo Agro Sinaloa 2023 su calidad en innovaci\u00f3n e investigaci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"images\/2022\/2023\/Feb23\/expouasagro.jpg\" alt=\"expouasagro\" style=\"display: block; margin: 20px auto;\" \/><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><span lang=\"ES\">La Universidad Aut\u00f3noma de Sinaloa (UAS) por primera vez apoya de manera directa en la organizaci\u00f3n de la Expo Agro Sinaloa 2023, el&nbsp;<\/span><span lang=\"ES-TRAD\">foro de agronegocios m\u00e1s importante de M\u00e9xico, que fue inaugurado por el Gobernador del Estado, doctor Rub\u00e9n Rocha Moya y el Secretario de Agricultura y Desarrollo Rural, V\u00edctor Manuel Villalobos Ar\u00e1mbula, y al que asisti\u00f3 el Rector, doctor Jes\u00fas Madue\u00f1a Molina.<\/span><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Por 31 a\u00f1os consecutivos la M\u00e1xima Casa de Estudios Sinaloense ha tenido presencia en la Expo Agro para mostrar a los visitantes locales, nacionales e internacionales la calidad de la formaci\u00f3n de recursos humanos en el \u00e1mbito agr\u00edcola y pecuario, as\u00ed como la innovaci\u00f3n e investigaci\u00f3n que se realiza por los universitarios.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">El Rector se\u00f1al\u00f3 que la Universidad aprovecha este espacio para dar a conocer lo que los alumnos, docentes e investigadores trabajan en las aulas y laboratorios de las \u00e1reas de agronom\u00eda, veterinaria, ingenier\u00eda y qu\u00edmica. &nbsp;<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cLa UAS es punta de lanza en el estado porque es la m\u00e1s importante por el n\u00famero de investigadores que tenemos (\u2026) m\u00e1s del 50 por ciento de los investigadores del estado son de la UAS, y eso sin lugar a dudas nos enorgullece\u201d, expres\u00f3 Madue\u00f1a Molina al expresar que este a\u00f1o aceptaron la invitaci\u00f3n de formar parte de este gran evento al cual se apoya principalmente con la difusi\u00f3n y transmisi\u00f3n de las actividades y se espera para el pr\u00f3ximo a\u00f1o participar en la organizaci\u00f3n de manera m\u00e1s importante.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><span lang=\"ES\">As\u00ed mismo agreg\u00f3 que esta es una forma de fortalecer la vinculaci\u00f3n con los sectores productivos a quienes se les convoc\u00f3 a participar el pr\u00f3ximo 6 de marzo al Foro Universitario de Reforma Acad\u00e9mica y Administrativa que tiene la finalidad de&nbsp;<\/span><span lang=\"ES-TRAD\">transformar los planes y programas de estudio y que de este ejercicio nazca la denominada Educaci\u00f3n Dual, para lo cual se requiere del apoyo de los empresarios de todos los sectores productivos.<\/span><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Durante la ceremonia de inauguraci\u00f3n el Gobernador, Rocha Moya, enfatiz\u00f3 que la Expo Agro contribuye en gran forma a que el estigma que se tiene de Sinaloa desaparezca y se refiri\u00f3 a la UAS como \u201csemillero de alto nivel\u201d<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cAqu\u00ed hay productores de alto nivel, aqu\u00ed se hace investigaci\u00f3n de biotecnolog\u00eda, aqu\u00ed tenemos un semillero de investigadores de alto nivel en la Facultad de Agronom\u00eda de la UAS\u201d, manifest\u00f3.<\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-TRAD\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES\" style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">A su llegada a la Expo Agro, el Gobernador y su comitiva visit\u00f3 el stand de la Universidad donde ya lo esperaba el Rector, docentes, investigadores y alumnos, y donde el Secretario de Agricultura del Gobierno Federal felicit\u00f3 a todos los estudiantes de la Facultad de Agronom\u00eda porque el pa\u00eds \u201cest\u00e1 necesitando cada vez m\u00e1s personas mejor preparadas para la nueva agricultura que se est\u00e1 generando\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/p>\n<div><br aria-hidden=\"true\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Aut\u00f3noma de Sinaloa (UAS) por primera vez apoya de manera directa en la organizaci\u00f3n de la Expo Agro Sinaloa 2023, el&nbsp;foro de agronegocios m\u00e1s importante de M\u00e9xico, que fue inaugurado por el Gobernador del Estado, doctor Rub\u00e9n Rocha Moya y el Secretario de Agricultura y Desarrollo Rural, V\u00edctor Manuel Villalobos Ar\u00e1mbula, y al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4157"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4157\/revisions"}],"predecessor-version":[{"id":28222,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4157\/revisions\/28222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4156"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4157"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}