{"id":4121,"date":"2023-02-20T20:04:11","date_gmt":"2023-02-20T20:04:11","guid":{"rendered":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/02\/20\/confirma-la-sociedad-su-confianza-en-la-educacion-de-calidad-que-brinda-la-uas\/"},"modified":"2025-06-24T22:26:15","modified_gmt":"2025-06-24T22:26:15","slug":"confirma-la-sociedad-su-confianza-en-la-educacion-de-calidad-que-brinda-la-uas","status":"publish","type":"post","link":"https:\/\/visionciudadana.com.mx\/oficial\/2023\/02\/20\/confirma-la-sociedad-su-confianza-en-la-educacion-de-calidad-que-brinda-la-uas\/","title":{"rendered":"Confirma la sociedad su confianza en la educaci\u00f3n de calidad que brinda la UAS\u00a0"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"images\/2022\/2023\/Feb23\/confirmauas.jpg\" alt=\"confirmauas\" width=\"720\" height=\"480\" style=\"display: block; margin: 20px auto;\" \/><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Un proceso fluido y sin contratiempos se registr\u00f3 en el primer d\u00eda de apertura del proceso de entrega de fichas en la Universidad Aut\u00f3noma de Sinaloa (UAS) para los aspirantes a ingresar al Nivel Medio Superior, y en un corte a las 10:56 horas de las m\u00e1s de 12 mil fichas para la Unidad Regional Centro (URC) ya se hab\u00edan asignado el 60 por ciento.<\/span><\/p>\n<p class=\"p4\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">El director general de Servicios Escolares, doctor Alfonso Mercado G\u00f3mez, inform\u00f3 que el Proceso de Preinscripci\u00f3n arranc\u00f3 como lo marca la Convocatoria emitida por la Comisi\u00f3n Institucional de Admisi\u00f3n: el sistema y plataforma se abrieron en punto de las 8:00 horas para la zona centro y se mantiene abierta.<\/span><\/p>\n<p class=\"p4\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cLas diferentes zonas se abrir\u00e1n de manera escalonada: ma\u00f1ana la Centro Norte, el mi\u00e9rcoles la zona norte y la sur el jueves (\u2026) tanto la Comisi\u00f3n Institucional de Admisi\u00f3n como nuestro Rector, el doctor Jes\u00fas Madue\u00f1a Molina, han estado muy al pendiente del proceso y su comportamiento; las plataformas funcionaron al 100 por ciento no hubo ning\u00fan contratiempo\u201d, expres\u00f3 Mercado G\u00f3mez.<\/span><\/p>\n<p class=\"p4\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Como muestra de la eficiencia en la plataforma, las fichas se agotaron entre los primeros 5 y 40 minutos en las preparatorias Rafael Buelna, Augusto C\u00e9sar Sandino, Central Diurna, Salvador Allende y su extensi\u00f3n, la Central Nocturna, Emiliano Zapata, Hnos. Flores Mag\u00f3n, por lo tanto, ya no aparecen como opci\u00f3n en el sistema.<\/span><\/p>\n<p class=\"p4\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cPara la zona Centro fueron poco m\u00e1s de 12 mil fichas que se pusieron a disposici\u00f3n, ya va alrededor del 60 por ciento de fichas asignadas, hacemos el llamado a todos los aspirantes que deseen ingresar a preparatoria que todav\u00eda tenemos alrededor de 5 mil fichas disponibles, claro, en las unidades agotadas no van a poder tener acceso, pero hay toda una oferta educativa aun disponible\u201d, enfatiz\u00f3.<\/span><\/p>\n<p class=\"p4\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">La mesa de ayuda ha estado funcionando al cien por ciento y el chat por WhatsApp atendiendo en tiempo real a los que tienen dudas, ha fluido la informaci\u00f3n y el proceso y esta atenci\u00f3n se mantiene.<\/span><\/p>\n<p class=\"p4\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">\u201cEl llamado a los padres de familia que est\u00e9n al pendiente de que sus hijos completen el proceso de preinscripci\u00f3n, que no se queden en esta primera etapa que es la obtenci\u00f3n de la ficha, tienen que continuar para descargar los documentos correspondientes como es la constancia de preinscripci\u00f3n, el recibo de pago, la ficha misma, y despu\u00e9s de pagar su recibo deben esperar 24 horas para ingresar de nuevo, llenar la solicitud y obtener el pase de examen de admisi\u00f3n\u201d, precis\u00f3 Mercado G\u00f3mez.<\/span><\/p>\n<p class=\"p4\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Para completar el proceso el aspirante debe tener a la mano el Kardex de secundaria o constancia con calificaciones, CURP y acta de nacimiento que deber\u00e1n subir en PDF.<\/span><\/p>\n<p class=\"p4\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">El director de Servicios Escolares consider\u00f3 que el hecho de que en los primeros 40 minutos se hayan agotado el 60 por ciento de fichas es reflejo de la confianza que la sociedad sinaloense y los padres de familia tienen en la educaci\u00f3n que la Universidad Aut\u00f3noma de Sinaloa imparte a sus hijos y el compromiso social que el Rector ha reiterado de garantizar una educaci\u00f3n de calidad y, en el caso del Nivel Bachillerato, garantizar un espacio a todo el aspirante que haya culminado su proceso.<\/span><\/p>\n<p class=\"p4\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\"><\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">Este martes 21 de febrero se abrir\u00e1 el portal para la Unidad Regional Centro Norte, el mi\u00e9rcoles 22 para la Unidad Regional Norte y el jueves 23 para la Unidad Regional Sur.<span class=\"Apple-converted-space\"><\/span><\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif;\">REDACCI\u00d3N\/VISI\u00d3N CIUDADANA.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un proceso fluido y sin contratiempos se registr\u00f3 en el primer d\u00eda de apertura del proceso de entrega de fichas en la Universidad Aut\u00f3noma de Sinaloa (UAS) para los aspirantes a ingresar al Nivel Medio Superior, y en un corte a las 10:56 horas de las m\u00e1s de 12 mil fichas para la Unidad Regional [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[31],"class_list":["post-4121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relevantes"],"aioseo_notices":[],"authors":[{"term_id":31,"user_id":1,"is_guest":0,"slug":"ivan3vino","display_name":"Iv\u00e1n Trevi\u00f1o","avatar_url":{"url":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png","url2x":"https:\/\/visionciudadana.com.mx\/oficial\/wp-content\/uploads\/2025\/09\/columna-ivan-Trevino.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/comments?post=4121"}],"version-history":[{"count":1,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4121\/revisions"}],"predecessor-version":[{"id":28239,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/posts\/4121\/revisions\/28239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media\/4120"}],"wp:attachment":[{"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/media?parent=4121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/categories?post=4121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/tags?post=4121"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visionciudadana.com.mx\/oficial\/wp-json\/wp\/v2\/ppma_author?post=4121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}